{"id":56,"count":1,"description":"","link":"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/","name":"Cocktail","slug":"cocktail","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cocktail Archives \u2022 3D Portfolio<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cocktail Archives \u2022 3D Portfolio\" \/>\n<meta property=\"og:url\" content=\"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/\" \/>\n<meta property=\"og:site_name\" content=\"3D Portfolio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@JulianHzg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/\",\"url\":\"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/\",\"name\":\"Cocktail Archives \u2022 3D Portfolio\",\"isPartOf\":{\"@id\":\"https:\/\/artificialflight.org\/blender\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/artificialflight.org\/blender\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cocktail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/artificialflight.org\/blender\/#website\",\"url\":\"https:\/\/artificialflight.org\/blender\/\",\"name\":\"3D Portfolio\",\"description\":\"Artificialflight\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/artificialflight.org\/blender\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cocktail Archives \u2022 3D Portfolio","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Cocktail Archives \u2022 3D Portfolio","og_url":"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/","og_site_name":"3D Portfolio","twitter_card":"summary_large_image","twitter_site":"@JulianHzg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/","url":"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/","name":"Cocktail Archives \u2022 3D Portfolio","isPartOf":{"@id":"https:\/\/artificialflight.org\/blender\/#website"},"breadcrumb":{"@id":"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/artificialflight.org\/blender\/tag\/cocktail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/artificialflight.org\/blender\/"},{"@type":"ListItem","position":2,"name":"Cocktail"}]},{"@type":"WebSite","@id":"https:\/\/artificialflight.org\/blender\/#website","url":"https:\/\/artificialflight.org\/blender\/","name":"3D Portfolio","description":"Artificialflight","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artificialflight.org\/blender\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/artificialflight.org\/blender\/wp-json\/wp\/v2\/tags\/56"}],"collection":[{"href":"http:\/\/artificialflight.org\/blender\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/artificialflight.org\/blender\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/artificialflight.org\/blender\/wp-json\/wp\/v2\/posts?tags=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}